{"id":4020,"date":"2023-07-19T10:01:00","date_gmt":"2023-07-19T10:01:00","guid":{"rendered":"http:\/\/websimar01\/simar\/?page_id=4020"},"modified":"2026-05-08T21:42:02","modified_gmt":"2026-05-08T21:42:02","slug":"biorresiduos","status":"publish","type":"page","link":"https:\/\/www.simar-louresodivelas.pt\/index.php\/biorresiduos","title":{"rendered":"Biorres\u00edduos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4020\" class=\"elementor elementor-4020\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3c615d elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"a3c615d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-feb0209\" data-id=\"feb0209\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b6b724 elementor-widget elementor-widget-image\" data-id=\"7b6b724\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.simar-louresodivelas.pt\/wp-content\/uploads\/2023\/09\/BIORRESIDUOS.jpg\" title=\"BIORRESIDUOS\" alt=\"BIORRESIDUOS\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a0ec4d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a0ec4d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-256a232\" data-id=\"256a232\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e2406a elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"2e2406a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-drumstick-bite\"><\/i><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f450e5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f450e5e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd44bc6\" data-id=\"dd44bc6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-119f480 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"119f480\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a646de\" data-id=\"3a646de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d52d7c elementor-widget elementor-widget-text-editor\" data-id=\"5d52d7c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p align=\"justify\"><span style=\"color: #000000;\">Designam-se por <strong>biorres\u00edduos<\/strong>, os res\u00edduos biodegrad\u00e1veis de jardins e parques (res\u00edduos verdes ou de jardim), os res\u00edduos alimentares e de cozinha das habita\u00e7\u00f5es, dos escrit\u00f3rios, dos restaurantes, dos grossistas, das cantinas, das unidades de catering e retalho e os res\u00edduos similares das unidades de transforma\u00e7\u00e3o de alimentos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3175602 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3175602\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-256ec27\" data-id=\"256ec27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca2187b elementor-widget__width-initial elementor-widget elementor-widget-accordion\" data-id=\"ca2187b\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2111\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">RES\u00cdDUOS ORG\u00c2NICOS OU ALIMENTARES <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2111\"><p>Os res\u00edduos org\u00e2nicos ou res\u00edduos alimentares s\u00e3o restos de prepara\u00e7\u00e3o de refei\u00e7\u00f5es e sobras de alimentos (cascas de fruta, aparas de legumes, p\u00e3o, borras de caf\u00e9, etc.).<\/p><p>Em 2005, os SIMAR iniciaram a recolha seletiva de res\u00edduos org\u00e2nicos em cerca de 600 estabelecimentos do canal HORECA, dos dois munic\u00edpios, e nas habita\u00e7\u00f5es da Urbaniza\u00e7\u00e3o da Portela e Quinta do Almirante (Santo Ant\u00f3nio dos Cavaleiros).<\/p><p>No entanto, estes res\u00edduos ainda representam cerca de 40% do total de res\u00edduos urbanos produzidos na \u00e1rea de interven\u00e7\u00e3o dos SIMAR, pelo que, \u00e9 fundamental efetuar a sua separa\u00e7\u00e3o.<\/p><p>Para isso, foi criado o projeto-piloto<span style=\"text-decoration: underline; color: #316cb5;\"><a style=\"color: #316cb5;\" href=\"https:\/\/www.simar-louresodivelas.pt\/index.php\/valorizacao-biorresiduos\" target=\"_blank\" rel=\"noopener\"><strong> Os Org\u00e2nicos Devolvemos \u00e0 Natureza<\/strong><\/a><\/span>, cofinanciado pelo POSEUR\/UE que alargou, em 2023, a recolha destes res\u00edduos a 25 urbaniza\u00e7\u00f5es dos concelhos de Loures e Odivelas.<span style=\"text-decoration: underline; color: #316cb5;\"> <a style=\"color: #316cb5; text-decoration: underline;\" href=\"https:\/\/www.simar-louresodivelas.pt\/index.php\/valorizacao-biorresiduos\" target=\"_blank\" rel=\"noopener\">Veja como aderir.<\/a><\/span><\/p><p>Mais tarde, o projeto foi implementado na Urbaniza\u00e7\u00e3o do Infantado, em Loures.<\/p><p>Nas zonas abrangidas pelo projeto foram entregues baldes castanhos de 7 L para que as fam\u00edlias possam separar os restos de prepara\u00e7\u00e3o de refei\u00e7\u00f5es e sobras de alimentos. Estes res\u00edduos devem, depois, ser depositados nos contentores individuais atribu\u00eddos aos pr\u00e9dios ou moradias ou, ainda, nos novos equipamentos de proximidade instalados em algumas zonas. Para esses, \u00e9 necess\u00e1rio um cart\u00e3o de acesso que permite a abertura do contentor.<\/p><p>Se tem um estabelecimento HORECA, saiba que a separa\u00e7\u00e3o destes res\u00edduos \u00e9 obrigat\u00f3ria.<\/p><p>Se, ainda, n\u00e3o tem o seu contentor castanho contacte-nos pelo telefone n.\u00ba 219 848 500 ou envie email para: <br \/><span style=\"text-decoration: underline; color: #316cb5;\">geral@simar-louresodivelas.pt<\/span><br \/>Entramos em contacto consigo!\u00a0 <br \/>A recolha destes res\u00edduos \u00e9 efetuada, diariamente, de domingo a 6.\u00aa feira.<\/p><p>Estes res\u00edduos s\u00e3o encaminhados para a <span style=\"text-decoration: underline; color: #316cb5;\"><a style=\"color: #316cb5; text-decoration: underline;\" href=\"https:\/\/www.valorsul.pt\/pt\/areas-de-negocio\/tratamento-e-valorizacao-de-residuos-urbanos\/valorizacao-organica\/valorizacao-organica\/estacao-de-tratamento-e-valorizacao-organica\/\" target=\"_blank\" rel=\"noopener\">Esta\u00e7\u00e3o de Tratamento e Valoriza\u00e7\u00e3o Org\u00e2nica da Valorsul<\/a><\/span><strong><span style=\"color: #326da8;\"><em>.<\/em><\/span><\/strong> Aqui, s\u00e3o transformados em composto para uso agr\u00edcola produzindo, tamb\u00e9m, energia el\u00e9trica, a partir do biog\u00e1s que os res\u00edduos libertam. Dado tratar-se de um processo de valoriza\u00e7\u00e3o muito sens\u00edvel e para que o mesmo seja bem-sucedido \u00e9 fundamental cumprir as <span style=\"text-decoration: underline; color: #316cb5;\"><span style=\"text-decoration: underline;\">Regras de Deposi\u00e7\u00e3o<\/span><span style=\"text-decoration: underline;\">\/Separa\u00e7\u00e3o<\/span><\/span><strong><em>.\u00a0<\/em><\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2112\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2112\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">RES\u00cdDUOS VERDES <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2112\"><p>Os res\u00edduos verdes ou de jardim s\u00e3o todos aqueles que resultam da limpeza e manuten\u00e7\u00e3o de jardins e outras \u00e1reas verdes.<\/p><p>Por exemplo: aparas, troncos, ramos, relvas e ervas. A recolha seletiva de res\u00edduos verdes tem como objetivo reduzir a presen\u00e7a destes res\u00edduos no contentor do lixo, bem como, contribuir para a reutiliza\u00e7\u00e3o e reciclagem de res\u00edduos biodegrad\u00e1veis.<\/p><p>Contribua para valorizar os res\u00edduos verdes que produz no seu jardim! Solicite a sua recolha aos SIMAR pelo telefone 219 848 500 ou envie email para: <span style=\"text-decoration: underline; color: #000000;\"><a style=\"color: #000000; text-decoration: underline;\" href=\"mailto:geral@simar-louresodivelas.pt\">geral@simar-louresodivelas.pt<\/a><\/span><\/p><p>Esta recolha \u00e9 gratuita para todos os utilizadores dos servi\u00e7os de \u00e1guas e res\u00edduos dos SIMAR, com produ\u00e7\u00e3o de res\u00edduos urbanos inferior a 1100L\/dia e\u00a0ser\u00e1 efetuada em data e local a acordar. Ap\u00f3s a solicita\u00e7\u00e3o da recolha, o prazo m\u00e1ximo de resposta n\u00e3o ultrapassa os 5 dias \u00fateis.<\/p><p>Para os restantes utilizadores dos servi\u00e7os de \u00e1guas e res\u00edduos, e ap\u00f3s avalia\u00e7\u00e3o pelos SIMAR, a recolha ser\u00e1 efetuada mediante or\u00e7amento e de acordo com a estrutura tarif\u00e1ria em vigor.<\/p><p>Estes res\u00edduos s\u00e3o encaminhados para a <span style=\"text-decoration: underline; color: #000000;\"><a style=\"color: #000000; text-decoration: underline;\" href=\"https:\/\/www.valorsul.pt\/pt\/areas-de-negocio\/tratamento-e-valorizacao-de-residuos-urbanos\/valorizacao-organica\/valorizacao-organica\/estacao-de-tratamento-e-valorizacao-organica\/\" target=\"_blank\" rel=\"noopener\">Esta\u00e7\u00e3o de Tratamento e Valoriza\u00e7\u00e3o Org\u00e2nica<\/a><\/span> ou, em fun\u00e7\u00e3o das suas caracter\u00edsticas, para o <span style=\"color: #326da8;\"><a style=\"color: #326da8;\" href=\"https:\/\/www.valorsul.pt\/pt\/areas-de-negocio\/tratamento-e-valorizacao-de-residuos-urbanos\/triagem-de-materiais-reciclaveis\/triagem-de-materiais-reciclaveis\/centro-de-triagem-do-lumiar\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #000000; text-decoration: underline;\">Ecocentro <\/span><span style=\"color: #000000; text-decoration: underline;\">da Valorsul<\/span><\/span><\/a><\/span><strong><em>.<\/em><\/strong> Aqui s\u00e3o transformados em composto para uso agr\u00edcola produzindo tamb\u00e9m energia el\u00e9trica, a partir do biog\u00e1s que os res\u00edduos libertam.<\/p><p>Devem ser cumpridas as <span style=\"color: #ff9900;\"><span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"\/index.php\/residuos-urbanos-sensibilizacao\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">Regras de Deposi\u00e7\u00e3o\/Separa\u00e7\u00e3o<\/span><\/a><\/span>.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bae4006 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bae4006\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93fbe6b\" data-id=\"93fbe6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd03a00 elementor-widget__width-initial elementor-widget elementor-widget-accordion\" data-id=\"dd03a00\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2311\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2311\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">COMPOSTORES DOM\u00c9STICOS<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2311\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2311\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-282946e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"282946e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70a8ff2\" data-id=\"70a8ff2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b6b27f elementor-widget__width-initial elementor-widget elementor-widget-accordion\" data-id=\"4b6b27f\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7901\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7901\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">SOBRE O PROJETO<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7901\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7901\"><p>Este projeto surge no \u00e2mbito da campanha \u201cOs org\u00e2nicos devolvemos \u00e0 natureza\u201d e visa a forma\u00e7\u00e3o em compostagem, a oferta de um compostor dom\u00e9stico aos clientes que t\u00eam espa\u00e7o para o instalar e o apoio continuado dos SIMAR aos clientes que, atrav\u00e9s de inscri\u00e7\u00e3o, manifestem o interesse em reduzir os seus res\u00edduos dom\u00e9sticos, produzindo fertilizante que vir\u00e1 a ser utilizado no seu jardim, quintal ou logradouro.<\/p><p><strong>\u00c9 necess\u00e1rio ter espa\u00e7o com terra para instalar o compostor. <\/strong><\/p><p>Fazer compostagem dom\u00e9stica evita o encaminhamento para incinera\u00e7\u00e3o de res\u00edduos que podem ser valorizados. Os SIMAR prop\u00f5em inverter este processo na origem, proporcionando aos clientes forma de reciclarem estes res\u00edduos nas suas habita\u00e7\u00f5es, com vantagens econ\u00f3micas e ambientais.<\/p><p>Como funciona? \u00c9 simples! As sobras da prepara\u00e7\u00e3o de refei\u00e7\u00f5es, nomeadamente, frutas e legumes crus e sem serem temperados, devem ser colocadas no compostor. Cobrimo-los com pequenos ramos, ervas e folhas secas e deixamos a natureza agir.<\/p><p>Aceita este desafio, mas tem d\u00favidas? <span style=\"text-decoration: underline;\">Increva-se (link para formul\u00e1rio)<\/span> e assista \u00e0 forma\u00e7\u00e3o que os SIMAR oferecem juntamente com o compostor.<\/p><p><div class=\"_3d-flip-book  fb3d-fullscreen-mode full-size\" data-id=\"41603\" data-mode=\"fullscreen\" data-title=\"false\" data-template=\"short-white-book-view\" data-lightbox=\"dark-shadow\" data-urlparam=\"fb3d-page\" data-page-n=\"0\" data-pdf=\"\" data-tax=\"null\" data-thumbnail=\"\" data-cols=\"3\" data-book-template=\"default\" data-trigger=\"\"><\/div><script type=\"text\/javascript\">window.FB3D_CLIENT_DATA = window.FB3D_CLIENT_DATA || [];FB3D_CLIENT_DATA.push('eyJwb3N0cyI6eyI0MTYwMyI6eyJJRCI6NDE2MDMsInRpdGxlIjoiR3VpYSBwclx1MDBlMXRpY28gZGEgY29tcG9zdGFnZW0iLCJ0eXBlIjoicGRmIiwicmVhZHlfZnVuY3Rpb24iOiIiLCJib29rX3N0eWxlIjoiZmxhdCIsImJvb2tfdGVtcGxhdGUiOiJub25lIiwib3V0bGluZSI6W10sImRhdGEiOnsicG9zdF9JRCI6IjQxNjA0IiwiZ3VpZCI6Imh0dHBzOlwvXC93d3cuc2ltYXItbG91cmVzb2RpdmVsYXMucHRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA0XC9BRl9tYW51YWxfQTVfaW1wcmVzc2FvLTEucGRmIiwicGRmX3BhZ2VzIjoiMTYiLCJwYWdlc19jdXN0b21pemF0aW9uIjoibm9uZSJ9LCJ0aHVtYm5haWwiOnsiZGF0YSI6eyJwb3N0X0lEIjoiMCJ9LCJ0eXBlIjoiYXV0byJ9LCJwcm9wcyI6eyJiYWNrZ3JvdW5kQ29sb3IiOiJhdXRvIiwiYmFja2dyb3VuZEltYWdlIjoiYXV0byIsImJhY2tncm91bmRTdHlsZSI6ImF1dG8iLCJoaWdobGlnaHRMaW5rcyI6ImF1dG8iLCJsaWdodGluZyI6ImF1dG8iLCJzaW5nbGVQYWdlTW9kZSI6ImF1dG8iLCJjYWNoZWRQYWdlcyI6ImF1dG8iLCJyZW5kZXJJbmFjdGl2ZVBhZ2VzIjoiYXV0byIsInJlbmRlckluYWN0aXZlUGFnZXNPbk1vYmlsZSI6ImF1dG8iLCJyZW5kZXJXaGlsZUZsaXBwaW5nIjoiYXV0byIsInByZWxvYWRQYWdlcyI6ImF1dG8iLCJhdXRvUGxheUR1cmF0aW9uIjoiYXV0byIsInJ0bCI6ImF1dG8iLCJpbnRlcmFjdGl2ZUNvcm5lcnMiOiJhdXRvIiwibWF4RGVwdGgiOiJhdXRvIiwic2hlZXQiOnsic3RhcnRWZWxvY2l0eSI6ImF1dG8iLCJ3YXZlIjoiYXV0byIsInNoYXBlIjoiYXV0byIsIndpZHRoVGV4ZWxzIjoiYXV0byIsImNvbG9yIjoiYXV0byIsInNpZGUiOiJhdXRvIiwic3RyZXRjaEltYWdlcyI6ImF1dG8iLCJjb3JuZXJEZXZpYXRpb24iOiJhdXRvIiwiZmxleGliaWxpdHkiOiJhdXRvIiwiZmxleGlibGVDb3JuZXIiOiJhdXRvIiwiYmVuZGluZyI6ImF1dG8iLCJoZWlnaHRUZXhlbHMiOiJhdXRvIn0sImNvdmVyIjp7IndhdmUiOiJhdXRvIiwiY29sb3IiOiJhdXRvIiwic2lkZSI6ImF1dG8iLCJzdHJldGNoSW1hZ2VzIjoiYXV0byIsImJpbmRlclRleHR1cmUiOiJhdXRvIiwiZGVwdGgiOiJhdXRvIiwicGFkZGluZyI6ImF1dG8iLCJzdGFydFZlbG9jaXR5IjoiYXV0byIsImZsZXhpYmlsaXR5IjoiYXV0byIsImZsZXhpYmxlQ29ybmVyIjoiYXV0byIsImJlbmRpbmciOiJhdXRvIiwid2lkdGhUZXhlbHMiOiJhdXRvIiwiaGVpZ2h0VGV4ZWxzIjoiYXV0byIsIm1hc3MiOiJhdXRvIiwic2hhcGUiOiJhdXRvIn0sInBhZ2UiOnsid2F2ZSI6ImF1dG8iLCJjb2xvciI6ImF1dG8iLCJzaWRlIjoiYXV0byIsInN0cmV0Y2hJbWFnZXMiOiJhdXRvIiwiZGVwdGgiOiJhdXRvIiwic3RhcnRWZWxvY2l0eSI6ImF1dG8iLCJmbGV4aWJpbGl0eSI6ImF1dG8iLCJmbGV4aWJsZUNvcm5lciI6ImF1dG8iLCJiZW5kaW5nIjoiYXV0byIsIndpZHRoVGV4ZWxzIjoiYXV0byIsImhlaWdodFRleGVscyI6ImF1dG8iLCJtYXNzIjoiYXV0byIsInNoYXBlIjoiYXV0byJ9LCJoZWlnaHQiOiJhdXRvIiwid2lkdGgiOiJhdXRvIiwiZ3Jhdml0eSI6ImF1dG8iLCJwYWdlc0ZvclByZWRpY3RpbmciOiJhdXRvIn0sImNvbnRyb2xQcm9wcyI6eyJhY3Rpb25zIjp7ImNtZFRvYyI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8iLCJhY3RpdmUiOiJhdXRvIiwiZGVmYXVsdFRhYiI6ImF1dG8ifSwiY21kQXV0b1BsYXkiOnsiZW5hYmxlZCI6ImF1dG8iLCJlbmFibGVkSW5OYXJyb3ciOiJhdXRvIiwiYWN0aXZlIjoiYXV0byJ9LCJjbWRTYXZlIjp7ImVuYWJsZWQiOiJhdXRvIiwiZW5hYmxlZEluTmFycm93IjoiYXV0byJ9LCJjbWRQcmludCI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8ifSwiY21kU2luZ2xlUGFnZSI6eyJlbmFibGVkIjoiYXV0byIsImVuYWJsZWRJbk5hcnJvdyI6ImF1dG8iLCJhY3RpdmUiOiJhdXRvIiwiYWN0aXZlRm9yTW9iaWxlIjoiYXV0byJ9LCJ3aWRUb29sYmFyIjp7ImVuYWJsZWQiOiJhdXRvIiwiZW5hYmxlZEluTmFycm93IjoiYXV0byJ9fX0sImF1dG9UaHVtYm5haWwiOiJodHRwczpcL1wvd3d3LnNpbWFyLWxvdXJlc29kaXZlbGFzLnB0XC93cC1jb250ZW50XC91cGxvYWRzXC8zZC1mbGlwLWJvb2tcL2F1dG8tdGh1bWJuYWlsc1wvNDE2MDMucG5nIiwicG9zdF9uYW1lIjoiZ3VpYS1wcmF0aWNvLWRhLWNvbXBvc3RhZ2VtIiwicG9zdF90eXBlIjoiM2QtZmxpcC1ib29rIn19LCJwYWdlcyI6W10sImZpcnN0UGFnZXMiOltdfQ==');window.FB3D_CLIENT_LOCALE && FB3D_CLIENT_LOCALE.render && FB3D_CLIENT_LOCALE.render();<\/script><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7902\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-7902\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">INSCRI\u00c7\u00c3O<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7902\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-7902\"><p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f36224-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"36224\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/4020#wpcf7-f36224-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"36224\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f36224-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:36224,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_rollback-cf7-5.8&quot;:true}}\" \/>\n<\/fieldset>\n<div id=\"responsive-form\" class=\"clearfix\" style=\"text-align: left\">\n\t<div class=\"column-full\">\n\t\t<h2 style=\"text-align: center\">INSCRI\u00c7\u00c3O PARA RECEBER COMPOSTOR DOM\u00c9STICO\n\t\t<\/h2>\n\t\t<p>Os campos com * s\u00e3o de preenchimento obrigat\u00f3rio.\n\t\t<\/p>\n\t\t<p>Se mora nos concelhos de Loures e Odivelas, inscreva-se:\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ncliente\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00famero de cliente*\" value=\"\" type=\"text\" name=\"ncliente\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-full\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"nome\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome*\" value=\"\" type=\"text\" name=\"nome\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"profissao\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Profiss\u00e3o*\" value=\"\" type=\"text\" name=\"profissao\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"datanascimento\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Data Nascimento*\" value=\"\" type=\"text\" name=\"datanascimento\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"ncontato\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telem\u00f3vel\/Telefone*\" value=\"\" type=\"text\" name=\"ncontato\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-full\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"morada\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Morada*\" value=\"\" type=\"text\" name=\"morada\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"porta\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00ba Morada e Andar*\" value=\"\" type=\"text\" name=\"porta\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"cp\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cod.Postal*\" value=\"\" type=\"text\" name=\"cp\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\n <!-- campos concelho e freguesia -->\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<div class=\"linha-campos\">\n\t\t\t\t<p><label for=\"concelho\">Concelho*<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"concelho\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"concelho\" aria-required=\"true\" aria-invalid=\"false\" name=\"concelho\"><option value=\"\">Selecione<\/option><option value=\"Loures\">Loures<\/option><option value=\"Odivelas\">Odivelas<\/option><\/select><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<div class=\"linha-campos\">\n\t\t\t\t<p><label for=\"freguesia_select\">Freguesia*<\/label><br \/>\n<select id=\"freguesia_select\" class=\"freguesia-html\" required>\n <option value=\"\">Selecione primeiro o concelho<\/option>\n <\/select><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"freguesia\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required freguesia-cf7\" id=\"freguesia\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"freguesia\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n <!-- Dados da habita\u00e7\u00e3o -->\n\t\t<div class=\"column-full\" style=\"margin-top: -10px;\">\n\t\t\t<p><label>DADOS DA HABITA\u00c7\u00c3O<\/label>\n\t\t\t<\/p>\n\t\t<\/div>\n\n <!-- Tipo de habita\u00e7\u00e3o -->\n\t\t<div class=\"column-half\" style=\"margin-top: -10px;\">\n\t\t\t<div class=\"linha-campos\">\n\t\t\t\t<p><label for=\"habitacao\">Tipo de habita\u00e7\u00e3o*:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"habitacao\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"habitacao\" aria-required=\"true\" aria-invalid=\"false\" name=\"habitacao\"><option value=\"Escolha\">Escolha<\/option><option value=\"Apartamento\">Apartamento<\/option><option value=\"Moradia\">Moradia<\/option><option value=\"Outro\">Outro<\/option><\/select><\/span><br \/>\n<span id=\"habitacao_outro_wrap\" style=\"display:none;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"habitacao_outro\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Qual?\" value=\"\" type=\"text\" name=\"habitacao_outro\" \/><\/span><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n \n\n <!-- Espa\u00e7o dispon\u00edvel -->\n\t\t<div class=\"column-half\" style=\"margin-top: -10px;\">\n\t\t\t<div class=\"linha-campos\">\n\t\t\t\t<p><label for=\"espaco\">Espa\u00e7o dispon\u00edvel para o compostor*:<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"espaco\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"espaco\" aria-required=\"true\" aria-invalid=\"false\" name=\"espaco\"><option value=\"Escolha\">Escolha<\/option><option value=\"Jardim\">Jardim<\/option><option value=\"Quintal\">Quintal<\/option><option value=\"Logradouro\">Logradouro<\/option><option value=\"Outro\">Outro<\/option><\/select><\/span><br \/>\n<span id=\"espaco_outro_wrap\" style=\"display:none;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"espaco_outro\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Qual?\" value=\"\" type=\"text\" name=\"espaco_outro\" \/><\/span><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n \n <!-- Numero de habitantes -->\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nhabitante\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"N\u00ba de habitantes da habita\u00e7\u00e3o*\" value=\"\" type=\"text\" name=\"Nhabitante\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\" style=\"margin-top: -15px;\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Observacoes\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Observa\u00e7\u00f5es\" value=\"\" type=\"text\" name=\"Observacoes\" \/><\/span>\n\t\t\t<\/p>\n\t\t\t<p style=\"font-size:10px;margin-top:5px;\" for=\"Observacoes\">Nota:<br \/>\n<i>Dever\u00e1 utilizar este espa\u00e7o para transmitir informa\u00e7\u00f5es que ache importantes. N\u00e3o deve escrever moradas, contatos ou outro tipo de informa\u00e7\u00e3o confidencial.<br \/>\n<\/i><i><br \/>\n<\/i>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<style>\n \/* Campos lado a lado (Contact Form 7) *\/\n .linha-campos {\n display: flex;\n align-items: center;\n gap: 10px;\n flex-wrap: nowrap;\n margin-bottom: 10px;\n }\n\n .linha-campos label {\n white-space: nowrap;\n min-width: 200px;\n font-weight: 500;\n }\n\n \/* Corrige comportamento do CF7 *\/\n .linha-campos .wpcf7-form-control-wrap {\n display: inline-block !important;\n width: auto !important;\n margin: 0 !important;\n padding: 0 !important;\n }\n\n .linha-campos select,\n .linha-campos input[type=\"text\"] {\n max-width: 400px; \n min-width: 320px; \n padding: 6px 8px;\n border: 1px solid #ccc;\n border-radius: 4px;\n font-size: 14px;\n }\n\n #habitacao_outro_wrap,\n #espaco_outro_wrap {\n display: inline-block;\n }\n.freguesia-cf7 {\n position: absolute !important;\n left: -9999px !important;\n width: 1px !important;\n height: 1px !important;\n opacity: 0 !important;\n pointer-events: none !important;\n}\n\n.freguesia-html {\n max-width: 400px; \n min-width: 320px; \n padding: 6px 8px;\n border: 1px solid #ccc;\n border-radius: 4px;\n font-size: 14px;\n}\n<\/style>\n<p><script>\ndocument.addEventListener('DOMContentLoaded', function() {\n const habitacao = document.querySelector('select[name=\"habitacao\"]');\n const habitacaoOutroWrap = document.getElementById('habitacao_outro_wrap');\n const espaco = document.querySelector('select[name=\"espaco\"]');\n const espacoOutroWrap = document.getElementById('espaco_outro_wrap');\n\n const concelho = document.querySelector('select[name=\"concelho\"]');\n const freguesiaSelect = document.getElementById('freguesia_select');\n const freguesiaCf7 = document.querySelector('input[name=\"freguesia\"]');\n\n const freguesiasPorConcelho = {\n \"Loures\": [\n \"Apela\u00e7\u00e3o\",\n \"Bobadela\",\n \"Bucelas\",\n \"Camarate\",\n \"Fanh\u00f5es\", \n \"Frielas\",\n \"Loures\",\n \"Lousa\", \n \"Moscavide\",\n \"Portela\",\n \"Prior Velho\",\n \"Sacav\u00e9m\",\n \"S\u00e3o Jo\u00e3o da Talha\",\n \"S\u00e3o Juli\u00e3o do Tojal\",\n \"Santa Iria de Azoia\", \n \"Santo Ant\u00e3o do Tojal\",\n \"Santo Ant\u00f3nio dos Cavaleiros\",\n \"Unhos\"\n ],\n \"Odivelas\": [\n \"Cane\u00e7as\",\n \"Fam\u00f5es\",\n \"Odivelas\",\n \"Olival Basto\",\n \"Pontinha\",\n \"P\u00f3voa de Santo Adri\u00e3o\",\n \"Ramada\"\n ]\n };\n\n if (habitacao) {\n habitacao.addEventListener('change', function() {\n habitacaoOutroWrap.style.display = (this.value === 'Outro') ? 'inline-block' : 'none';\n });\n }\n\n if (espaco) {\n espaco.addEventListener('change', function() {\n espacoOutroWrap.style.display = (this.value === 'Outro') ? 'inline-block' : 'none';\n });\n }\n\n function atualizarFreguesias() {\n const concelhoSelecionado = concelho.value;\n freguesiaSelect.innerHTML = '';\n\n const opcaoInicial = document.createElement('option');\n opcaoInicial.value = '';\n opcaoInicial.textContent = 'Selecione a freguesia';\n freguesiaSelect.appendChild(opcaoInicial);\n\n if (freguesiasPorConcelho[concelhoSelecionado]) {\n freguesiasPorConcelho[concelhoSelecionado].forEach(function(nomeFreguesia) {\n const option = document.createElement('option');\n option.value = nomeFreguesia;\n option.textContent = nomeFreguesia;\n freguesiaSelect.appendChild(option);\n });\n }\n\n if (freguesiaCf7) {\n freguesiaCf7.value = '';\n }\n }\n\n if (concelho) {\n concelho.addEventListener('change', atualizarFreguesias);\n }\n\n if (freguesiaSelect && freguesiaCf7) {\n freguesiaSelect.addEventListener('change', function() {\n freguesiaCf7.value = this.value;\n });\n }\n});\n<\/script>\n<\/p>\n<p><label style=\"text-align: center\">Devolva os Org\u00e2nicos \u00e0 Natureza. Aceite este desafio<\/label>\n<\/p>\n<p><label style=\"text-align: center\"><strong>Brevemente ser\u00e1 contactado\/a para o agendamento da sess\u00e3o de esclarecimento e entrega do compostor.<br \/>\n<\/strong><\/label>\n<\/p>\n<p><label style=\"font-size:12px;\"><u>NORMAS DE CONFIDENCIALIDADE<\/u><\/label>\n<\/p>\n<p style=\"font-size:12px;\">Os seus dados pessoais n\u00e3o ir\u00e3o aparecer em quaisquer relat\u00f3rios ou apresenta\u00e7\u00f5es que resultem deste projeto. Apenas ir\u00e1 aparecer informa\u00e7\u00e3o agregada ou an\u00f3nima.<br \/>\nO que ir\u00e1 acontecer com a informa\u00e7\u00e3o disponibilizada por si? Toda a informa\u00e7\u00e3o recolhida e processada no \u00e2mbito deste projeto ser\u00e1 trabalhada no estrito cumprimento do Regulamento Geral de Prote\u00e7\u00e3o de Dados. A informa\u00e7\u00e3o ser\u00e1 apresentada de uma forma an\u00f3nima e ser\u00e1 guardada nos termos da pol\u00edtica de privacidade (inserir link) dos SIMAR de Loures e Odivelas.<br \/>\nA participa\u00e7\u00e3o neste projeto \u00e9 volunt\u00e1ria.\n<\/p>\n<p><label style=\"text-align: center\"><strong>Pol\u00edtica de Privacidade<\/strong><\/label>\n<\/p>\n<div id=\"scroll\" style=\"overflow-y:scroll; height: 100px; text-align: justify; font-size:11px;padding-left:10px;padding-right:10px\">\n\t<p>Os Servi\u00e7os Intermunicipalizados de \u00c1gua e Res\u00edduos dos Munic\u00edpios de Loures e Odivelas (adiante designado por SIMAR) s\u00e3o um servi\u00e7o p\u00fablico n\u00e3o personalizado, de interesse local, dotado de autonomia t\u00e9cnica, administrativa e financeira e geridos sob a forma empresarial, no quadro da organiza\u00e7\u00e3o intermunicipal, inscrevendo-se na administra\u00e7\u00e3o direta dos respetivos munic\u00edpios.\n\t<\/p>\n\t<p>Os munic\u00edpios, como qualquer entidade p\u00fablica ou privada que proceda ao tratamento de dados pessoais, encontram-se abrangidos pelo Regulamento Geral sobre a Prote\u00e7\u00e3o de Dados.\n\t<\/p>\n\t<p>A Pol\u00edtica de Privacidade dos SIMAR rege-se pelos princ\u00edpios de prote\u00e7\u00e3o de dados enunciados no Regulamento Geral sobre a Prote\u00e7\u00e3o de Dados (doravante RGPD ou Regulamento ou regulamento, 2016\/679 do Parlamento Europeu e do Conselho de 27 de abril de 2016, relativo \u00e0 prote\u00e7\u00e3o das pessoas singulares no que diz respeito ao tratamento de dados pessoais e \u00e0 livre circula\u00e7\u00e3o desses dados.\n\t<\/p>\n\t<p>Consideram-se \u201cdados pessoais\u201d nos termos legais, todos e quaisquer dados relativos a pessoas singulares identificadas ou identific\u00e1veis.\n\t<\/p>\n\t<p>Os SIMAR poder\u00e3o alterar esta pol\u00edtica sempre que tal se justifique, e de modo a garantir o alinhamento com as leis, regulamentos e boas pr\u00e1ticas de neg\u00f3cio aplic\u00e1veis. Em caso de altera\u00e7\u00e3o da pol\u00edtica, os titulares de dados ser\u00e3o informados.\n\t<\/p>\n\t<p><strong>1. \u00c2mbito:<\/strong> Esta pol\u00edtica aplica-se a todo e qualquer tratamento de dados pessoais pelos SIMAR.\n\t<\/p>\n\t<p><strong>2. Respons\u00e1vel pelo tratamento de dados:<\/strong> A entidade respons\u00e1vel pelo tratamento dos dados pessoais s\u00e3o os SIMAR que assegura que o tratamento dos seus Dados Pessoais \u00e9 efetuado no \u00e2mbito da finalidade para os quais os mesmos foram recolhidos ou para finalidades compat\u00edveis com o prop\u00f3sito inicial para que foram recolhidos;\n\t<\/p>\n\t<p>Os titulares dos dados poder\u00e3o apresentar quest\u00f5es relativas aos mesmos, por escrito, para a morada R.Ilha da Madeira, n\u00ba2, 2674-504 Loures ou atrav\u00e9s do endere\u00e7o eletr\u00f3nico epd@simar-louresodivelas.pt\n\t<\/p>\n\t<p><strong>3. Recolha e Tratamento de dados Pessoais: <\/strong>Os dados pessoais recolhidos no \u00e2mbito do presente contrato destinam-se \u00e0 gest\u00e3o da rela\u00e7\u00e3o contratual, a a\u00e7\u00f5es de informa\u00e7\u00e3o e \u00e0 presta\u00e7\u00e3o dos servi\u00e7os contratados, sendo o seu tratamento realizado de acordo com o RGPD.\n\t<\/p>\n\t<p>Caso n\u00e3o se enquadre no par\u00e1grafo anterior, o tratamento dos dados pessoais s\u00f3 poder\u00e1 ser realizado ap\u00f3s a obten\u00e7\u00e3o do consentimento expl\u00edcito do titular dos dados para a finalidade expressamente comunicada ao mesmo.\n\t<\/p>\n\t<p>A tipologia de dados pessoais tratados pelos SIMAR inclui: dados de identifica\u00e7\u00e3o pessoal, dados financeiros\/pagamento, contactos e dados sens\u00edveis. A recolha destes dados \u00e9 realizada presencialmente, via email, por telefone e\/ou via website. Os dados pessoais fornecidos destinam-se ao uso exclusivo dos Servi\u00e7os Intermunicipalizados de \u00c1guas e Res\u00edduos de Loures e Odivelas ou de empresas subcontratadas no estrito \u00e2mbito da execu\u00e7\u00e3o de contratos, assegurando-se a confidencialidade dos dados. Os dados poder\u00e3o ser fornecidos a autoridades judiciais ou administrativas, nos casos previstos na lei.\n\t<\/p>\n\t<p><strong>4. Encarregado da Prote\u00e7\u00e3o de Dados: <\/strong> Nos termos da al\u00ednea a) do n.\u00ba 1 do artigo 37.\u00ba do Regulamento Geral sobre a Prote\u00e7\u00e3o de Dados Pessoais, foi designado um Encarregado da Prote\u00e7\u00e3o de Dados, podendo os titulares desses dados apresentar as quest\u00f5es relativas aos mesmos, por escrito, para os seguintes contactos: epd@simar-louresodivelas.pt.\n\t<\/p>\n\t<p><strong>5. Princ\u00edpios observados no tratamento dos Dados Pessoais: <\/strong> No tratamento de dados a que os SIMAR procedem, observam os princ\u00edpios da licitude, lealdade e transpar\u00eancia, limita\u00e7\u00e3o das finalidades, minimiza\u00e7\u00e3o dos dados, exatid\u00e3o, limita\u00e7\u00e3o da conserva\u00e7\u00e3o; integridade, confidencialidade e responsabilidade\n\t<\/p>\n\t<p><strong>6. Seguran\u00e7a de Dados Pessoais: <\/strong> Os SIMAR assumem o compromisso de garantir a prote\u00e7\u00e3o e seguran\u00e7a dos dados pessoais atrav\u00e9s da utiliza\u00e7\u00e3o de um conjunto de tecnologias e procedimentos de seguran\u00e7a adequados para proteger os seus Dados Pessoais do acesso, uso ou divulga\u00e7\u00e3o n\u00e3o autorizados, como cifragem dos dados, controlo de acessos e monitoriza\u00e7\u00e3o das bases de dados e sistemas de informa\u00e7\u00e3o, que garante uma completa auditoria e responsabiliza\u00e7\u00e3o dos acessos.\n\t<\/p>\n\t<p><strong>7.Direitos do titular dos Dados : <\/strong> Os SIMAR garantem aos titulares dos dados os direitos ao acesso, a retifica\u00e7\u00e3o, a limita\u00e7\u00e3o de tratamento e ainda o apagamento dos Dados Pessoais.\n\t<\/p>\n\t<p><strong>8. Subcontratantes: <\/strong> Os SIMAR recorrem a entidades subcontratadas para a presta\u00e7\u00e3o de servi\u00e7os que podem envolver o tratamento de dados pessoais. Os SIMAR tomam as medidas exig\u00edveis de modo a assegurar que as entidades subcontratantes cumpram as disposi\u00e7\u00f5es do RPGD.\n\t<\/p>\n\t<p><strong>9. Confidencialidade: <\/strong> Os SIMAR comprometem-se a assegurar a confidencialidade dos dados pessoais. O princ\u00edpio do m\u00ednimo acesso \u00e9 aplicado, garantindo que os colaboradores dos SIMAR s\u00f3 t\u00eam acesso aos dados necess\u00e1rios para o correto desempenho das suas fun\u00e7\u00f5es.\n\t<\/p>\n\t<p>A obriga\u00e7\u00e3o de confidencialidade dos trabalhadores dos SIMAR face aos dados recolhidos pela organiza\u00e7\u00e3o resulta da celebra\u00e7\u00e3o do contrato de trabalho e mant\u00e9m-se ap\u00f3s cessadas as suas fun\u00e7\u00f5es. Qualquer recolha, tratamento ou uso n\u00e3o autorizado de dados \u00e9 estritamente proibido e alvo de processo disciplinar\n\t<\/p>\n\t<p><strong>10. Prazo de conserva\u00e7\u00e3o dos dados: <\/strong> Os SIMAR v\u00e3o tratar e manter os dados pessoais pelo per\u00edodo durante o qual se mantiver a rela\u00e7\u00e3o contratual, tratando e armazenando os seus dados pessoais na medida do necess\u00e1rio para o cumprimento das aplic\u00e1veis previs\u00f5es contratuais e legais. Os Dados Pessoais poder\u00e3o ser mantidos pelos SIMAR de acordo com as exig\u00eancias legais inerentes \u00e0s finalidades do tratamento para que foram recolhidos.\n\t<\/p>\n<\/div>\n<div style=\"text-align: left; font-size:12px;margin-top: 20px;margin-left: 0px;\">\n\t<p><label> <span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-489\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-489\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Tomei conhecimento da informa\u00e7\u00e3o sobre a prote\u00e7\u00e3o de dados pessoais<\/label>\n\t<\/p>\n<\/div>\n<div id=\"responsive-form\" class=\"clearfix\">\n\t<div class=\"form-row\" >\n\t\t<div class=\"column-half\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7903\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-7903\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">PERGUNTAS FREQUENTES<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7903\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-7903\"><ol><li><strong>Como compostar?<\/strong><\/li><\/ol><p>No dia-a-dia juntam-se os desperd\u00edcios de vegetais, frutas e\/ou restos de jardim. De seguida, colocam-se no compostor. Cobrem-se com pequenos ramos e folhas secas e deixa-se a natureza agir. Poder\u00e1 aprender rapidamente, assistindo a uma a\u00e7\u00e3o de esclarecimentos obrigat\u00f3ria para posterior entrega do compostor.<\/p><p><strong>2. O que \u00e9 o composto? <\/strong><\/p><p>\u00c9 um excelente fertilizante que se obt\u00e9m atrav\u00e9s de um processo de transforma\u00e7\u00e3o natural e simples \u2013 a compostagem. O composto funciona como um adubo natural, nutrindo o solo, melhorando as propriedades f\u00edsicas e qu\u00edmicas da sua estrutura, evitando, desta forma, o uso de fertilizantes qu\u00edmicos.<\/p><p><strong>3. Quem pode candidatar-se? <\/strong><\/p><p>Todos os residentes nos concelhos de Loures e Odivelas. Basta increver-se (link para formul\u00e1rio) e posteriormente ser\u00e1 contactado\/a para assistir a uma sess\u00e3o de esclarecimentos e receber o compostor dom\u00e9stico.<\/p><p><strong>4. A sess\u00e3o de esclarecimentos \u00e9 obrigat\u00f3ria? Posso receber o compostor antes de assistir \u00e0 sess\u00e3o?\u00a0 <\/strong><\/p><p>Sim, a sess\u00e3o de esclarecimentos \u00e9 obrigat\u00f3ria e n\u00e3o poder\u00e1 receber o compostor sem assistir a uma sess\u00e3o presencial ou online.<\/p><p><strong>5. Qual a forma de concorrer? <\/strong><\/p><p>Basta preencher a inscri\u00e7\u00e3o (link) e aguardar o nosso contacto.<\/p><p><strong>6. Quais s\u00e3o os requisitos para receber o compostor gratuitamente? <\/strong><\/p><p>Para receber o compostar de forma gratuita \u00e9 obrigat\u00f3rio assistir a uma a\u00e7\u00e3o de forma\u00e7\u00e3o (de dura\u00e7\u00e3o m\u00ednima de uma hora). A forma\u00e7\u00e3o \u00e9 dada pelos SIMAR e por convite, com base nas candidaturas recebidas nesta plataforma, em inscri\u00e7\u00e3o. (link)<\/p><p><strong>7. Onde \u00e9 a a\u00e7\u00e3o de forma\u00e7\u00e3o? <\/strong><\/p><p>Quando for contactado\/a ser\u00e1 informado\/a do local e hor\u00e1rio da a\u00e7\u00e3o. Estas podem tamb\u00e9m ocorrer online atrav\u00e9s da plataforma Microsoft Teams.<\/p><p><strong>8. Quando ser\u00e1 entregue o compostor? <\/strong><\/p><p>O compostor \u00e9 entregue depois da a\u00e7\u00e3o de forma\u00e7\u00e3o presencial. No caso da a\u00e7\u00e3o ser online, ser\u00e1 agendada a entrega do compostor. Este \u00e9 entregue desmontado.<\/p><p><strong>9. O que acompanha o compostor? <\/strong><\/p><p>Com cada compostor receber\u00e1 um Guia Pr\u00e1tico de Compostagem Dom\u00e9stica. Na altura da entrega do compostor, ter\u00e1 de assinar um Termo de Responsabilidade em como se compromete a usar o compostor adequadamente.<\/p><p><strong>10. Serei contactado\/a depois da entrega do compostor? <\/strong><\/p><p>Sim, pode ser contactado para monitoriza\u00e7\u00e3o\/acompanhamento ou esclarecimento de d\u00favidas. O contacto ser\u00e1 efetuado atrav\u00e9s de e-mail. Poder\u00e3o tamb\u00e9m ser aplicados inqu\u00e9ritos por question\u00e1rio, para avaliar a satisfa\u00e7\u00e3o.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cdc0d56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdc0d56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59d9add\" data-id=\"59d9add\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85f4ca2 elementor-widget elementor-widget-html\" data-id=\"85f4ca2\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script src=\"data:text\/javascript;base64,alF1ZXJ5KGRvY3VtZW50KS5yZWFkeShmdW5jdGlvbigkKXt2YXIgZGVsYXk9MTAwO3NldFRpbWVvdXQoZnVuY3Rpb24oKXskKCcuZWxlbWVudG9yLXRhYi10aXRsZScpLnJlbW92ZUNsYXNzKCdlbGVtZW50b3ItYWN0aXZlJyk7JCgnLmVsZW1lbnRvci10YWItY29udGVudCcpLmNzcygnZGlzcGxheScsJ25vbmUnKX0sZGVsYXkpfSk=\" defer><\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Designam-se por biorres\u00edduos, os res\u00edduos biodegrad\u00e1veis de jardins e parques (res\u00edduos verdes ou de jardim), os res\u00edduos alimentares e de cozinha das habita\u00e7\u00f5es, dos escrit\u00f3rios, dos restaurantes, dos grossistas, das cantinas, das unidades de catering e retalho e os res\u00edduos similares das unidades de transforma\u00e7\u00e3o de alimentos. RES\u00cdDUOS ORG\u00c2NICOS OU ALIMENTARES Os res\u00edduos org\u00e2nicos ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-4020","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/pages\/4020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/comments?post=4020"}],"version-history":[{"count":136,"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/pages\/4020\/revisions"}],"predecessor-version":[{"id":42535,"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/pages\/4020\/revisions\/42535"}],"wp:attachment":[{"href":"https:\/\/www.simar-louresodivelas.pt\/index.php\/wp-json\/wp\/v2\/media?parent=4020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}